{"id":10003484,"date":"2025-03-21T17:23:08","date_gmt":"2025-03-21T16:23:08","guid":{"rendered":"https:\/\/qzm-rn.de\/?post_type=tribe_events&#038;p=9577"},"modified":"2026-05-13T14:58:22","modified_gmt":"2026-05-13T12:58:22","slug":"qzm-wohnzimmer-6","status":"publish","type":"tribe_events","link":"https:\/\/qzm-rn.de\/en\/veranstaltung\/qzm-wohnzimmer-6\/2026-09-20\/","title":{"rendered":"QZM Wohnzimmer"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t20. September\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t15:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t18:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p><em>English below!<\/em><\/p>\n\n\n\n<p>Ihr habt sonntags noch nichts vor? Ihr habt unfertige Projekte, die ihr alleine nicht fertigbekommt? Ihr wollt in Gesellschaft ein gutes Buch endlich mal anfangen oder fertiglesen? Die eine Idee f\u00fcr einen Text spukt euch seit Monaten im Kopf herum, aber ihr habt einfach keine Gelegenheit, sie zu Papier zu bringen?<\/p>\n\n\n\n<p>Dann kommt ins QZM Wohnzimmer! Ein Ort ohne Wertung oder ein schlechtes Gef\u00fchl f\u00fcr unfertige Projekte und mit viel Liebe und Akzeptanz \u2013 egal wer ihr seid oder was ihr macht. Um diese Stimmung beizubehalten, bitten wir darum, dass ihr auch mit dieser Einstellung zu uns ins Wohnzimmer kommt. Wir schaffen eine ruhige Atmosph\u00e4re, damit Menschen sich konzentrieren k\u00f6nnen.<\/p>\n\n\n\n<p>Bringt eure Projekte und Ideen mit und arbeitet daran. Lernt neue Menschen mit den gleichen Interessen kennen und kommt ins Gespr\u00e4ch. Das QZM Wohnzimmer ist ein Ort der Entspannung und des Wohngef\u00fchls, kommt mit euren gem\u00fctlichsten Wollsocken und f\u00fchlt euch wie zuhause.<\/p>\n\n\n\n<p>Getr\u00e4nke sind gegen Spenden erh\u00e4ltlich, also freut euch auf eine k\u00fchle Cola, einen leckeren Kaffee oder eine hei\u00dfe Schokolade.<\/p>\n\n\n\n<p>Wir freuen uns auf euch und eure Projekte.<\/p>\n\n\n\n<p>Information regarding accessibility: The venue is accessible without stairs and has barrier low toilet.<br>Questions about accessibility at QZM should be addressed to&nbsp;<a href=\"mailto:info@qzm-rn.de\">info@qzm-rn.de<\/a>&nbsp;or 0621 15677628.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>You have nothing to do on Sunday? You have unfinished projects that you can\u2019t finish alone? You want to finally start or finish that book in good company? You have a brilliant idea for a text that you couldn\u2019t write down just yet?<\/p>\n\n\n\n<p>Then come in on Sunday, May 18<sup>th<\/sup>, between 3 pm and 6 pm to the QZM Livingroom! A place without judgement or bad feeling for your unfinished projects and with a lot of love and acceptance \u2013 whoever you are or what you are doing. To keep this energy, we are asking you enter the Livingroom with the same attitude. We want to create a quiet and cozy atmosphere so that people can concentrate.<\/p>\n\n\n\n<p>Bring your projects and ideas to work on them. Meet new people with the same interests and get to talk with them. The QZM Livingroom is a space of relaxation and comfort, so come in your cozy wooly socks and feel at home.<\/p>\n\n\n\n<p>Drinks are available for donation, so are excited for a cool coke, a tasty coffee or a hot chocolate.<\/p>\n\n\n\n<p>We are excited to meet you and your projects.<\/p>\n\n\n\n<p>Information regarding accessibility: The venue is accessible without stairs and has barrier low toilet. Questions regarding accessibility in the QZM can be directed to&nbsp;<a href=\"mailto:info@qzm-rn.de\">info@qzm-rn.de<\/a>&nbsp;or 0621 15677628.<\/p>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t\t<span class=\"tribe-block__event-price__cost\"> Free <\/span>\n\t\t<\/div>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/qzm-rn.de\/en\/venue\/qzm\/\" title=\"QZM\">QZM<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">G7 ,14<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Mannheim<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\t<span class=\"tribe-postal-code\">68159<\/span>\n\n\t<span class=\"tribe-country-name\">Deutschland<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__website\"><a href=\"http:\/\/qzm-rn.de\/en\/\" target=\"_self\" rel=\"external\">View Venue Website<\/a><\/span><br \/>\n\t\t\t\n\t<\/div>\n\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdd to calendar\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260920T150000\/20260920T180000&#038;text=QZM%20Wohnzimmer&#038;details=%3Cp%3E%3Cem%3EEnglish+below%21%3C%2Fem%3E%3C%2Fp%3E+%3Cp%3EIhr+habt+sonntags+noch+nichts+vor%3F+Ihr+habt+unfertige+Projekte%2C+die+ihr+alleine+nicht+fertigbekommt%3F+Ihr+wollt+in+Gesellschaft+ein+gutes+Buch+endlich+mal+anfangen+oder+fertiglesen%3F+Die+eine+Idee+f%C3%BCr+einen+Text+spukt+euch+seit+Monaten+im+Kopf+herum%2C+aber+ihr+habt+einfach+keine+Gelegenheit%2C+sie+zu+Papier+zu+bringen%3F%3C%2Fp%3E+%3Cp%3EDann+kommt+ins+QZM+Wohnzimmer%21+Ein+Ort+ohne+Wertung+oder+ein+schlechtes+Gef%C3%BChl+f%C3%BCr+unfertige+Projekte+und+mit+viel+Liebe+und+Akzeptanz+%E2%80%93+egal+wer+ihr+seid+oder+was+ihr+macht.+Um+diese+Stimmung+beizubehalten%2C+bitten+wir+darum%2C+dass+ihr+auch+mit+dieser+Einstellung+zu+uns+ins+Wohnzimmer+kommt.+Wir+schaffen+eine+ruhige+Atmosph%C3%A4re%2C+damit+Menschen+sich+konzentrieren+k%C3%B6nnen.%3C%2Fp%3E+%3Cp%3EBringt+eure+Projekte+und+Ideen+mit+und+arbeitet+daran.+Lernt+neue+Menschen+mit+den+gleichen+Interessen+kennen+und+kommt+ins+Gespr%C3%A4ch.+Das+QZM+Wohnzimmer+ist+ein+Ort+der+Entspannung+und+des+Wohngef%C3%BChls%2C+kommt+mit+euren+gem%C3%BCtlichsten+Woll%3C%2Fp%3E+%28View+Full+event+Description+Here%3A+https%3A%2F%2Fqzm-rn.de%2Fen%2Fveranstaltung%2Fqzm-wohnzimmer-6%2F2026-09-20%2F%29&#038;location=QZM,%20G7%20,14,%20Mannheim,%2068159,%20Deutschland&#038;trp=false&#038;ctz=Europe\/Berlin&#038;sprop=website:https:\/\/qzm-rn.de\/en\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul  class=\"tribe-related-events tribe-clearfix\" >\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-11\/2026-05-14\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2024\/05\/Puppy-Stammtisch-HP-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-11\/2026-05-14\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tPuppy Meet Up\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">14. May @ 18:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/karaoke-party-im-qzm-19\/2026-05-15\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2025\/03\/Karaoke-Hp-1600-x-1066-px-1-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Auf der Graphik erkennt man auf lila-schwarzem Hintergund ein Mikrophon und die Aufschrift &quot;Karaoke - Rock the Stage&quot;.\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/karaoke-party-im-qzm-19\/2026-05-15\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tKaraoke im QZM\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">15. May @ 20:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/public-viewing-des-esc-finale\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2026\/05\/J580010-ESC-FACEBOOK-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/public-viewing-des-esc-finale\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tPublic Viewing des ESC Finale\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">16. May @ 19:00<\/span><\/div>\n<\/li>\n\t<\/ul>","protected":false},"excerpt":{"rendered":"<p>Kommt ins QZM Wohnzimmer! Ein Ort ohne Wertung oder ein schlechtes Gef\u00fchl f\u00fcr unfertige Projekte und mit viel Liebe und Akzeptanz &#8211; egal wer ihr seid oder was ihr macht. Bringt eure Projekte und Ideen mit und arbeitet daran. Lernt neue Menschen mit den gleichen Interessen kennen und kommt ins Gespr\u00e4ch.<\/p>","protected":false},"author":2,"featured_media":10153,"template":"","meta":{"_tec_requires_first_save":false,"_eb_attr":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_EventAllDay":false,"_EventTimezone":"Europe\/Berlin","_EventStartDate":"2026-09-20 15:00:00","_EventEndDate":"2026-09-20 18:00:00","_EventStartDateUTC":"2026-09-20 13:00:00","_EventEndDateUTC":"2026-09-20 16:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"0","_EventCostDescription":"","_EventCurrencySymbol":"EUR","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[2523],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"type\":\"monthly\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2025-05-18\",\"_start_date_input\":\"18. Mai 2025\",\"_start_date_obj\":null,\"start_time\":\"15:00:00\",\"_start_time_input\":\"15:00\",\"end_date\":\"2025-05-18\",\"_end_date_input\":\"18. Mai 2025\",\"_end_date_obj\":null,\"end_time\":\"18:00:00\",\"_end_time_input\":\"18:00\",\"between\":1,\"limit_type\":\"date\",\"limit\":\"2026-12-31\",\"_limit_date_input\":\"31. Dezember 2026\",\"_limit_date_obj\":\"2026-12-30T23:00:00.000Z\",\"days\":[7],\"week\":\"third\",\"day\":7,\"month\":[5],\"timezone\":\"Europe\/Berlin\",\"multi_day_span\":\"next_day\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"[{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2025-07-20\",\"_start_date_input\":\"20. Juli 2025\",\"_start_date_obj\":\"2025-07-19T22:00:00.000Z\",\"start_time\":\"15:00:00\",\"_start_time_input\":\"15:00\",\"end_date\":\"2025-05-18\",\"_end_date_input\":\"18. Mai 2025\",\"_end_date_obj\":null,\"end_time\":\"18:00:00\",\"_end_time_input\":\"18:00\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"18. Mai 2025\",\"_limit_date_obj\":null,\"days\":[7],\"week\":\"third\",\"day\":7,\"month\":[5],\"timezone\":\"Europe\/Berlin\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2025-11-16\",\"_start_date_input\":\"16. November 2025\",\"_start_date_obj\":\"2025-11-15T23:00:00.000Z\",\"start_time\":\"15:00:00\",\"_start_time_input\":\"15:00\",\"end_date\":\"2025-05-18\",\"_end_date_input\":\"18. Mai 2025\",\"_end_date_obj\":null,\"end_time\":\"18:00:00\",\"_end_time_input\":\"18:00\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"18. Mai 2025\",\"_limit_date_obj\":null,\"days\":[7],\"week\":\"third\",\"day\":7,\"month\":[5],\"timezone\":\"Europe\/Berlin\",\"multi_day_span\":\"next_day\",\"isOffStart\":false}]","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[34,36,21,48,10,11,134],"tribe_events_cat":[964,530],"class_list":["post-10003484","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-lsbti","tag-lsbttiq","tag-mannheim","tag-queer","tag-queeres-zentrum-mannheim","tag-qzm","tag-trans","tribe_events_cat-qzm-wohnzimmer","tribe_events_cat-veranstaltung","cat_qzm-wohnzimmer","cat_veranstaltung","tribe-recurring-event","tribe-recurring-event-parent"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/10003484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/10003484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media\/10153"}],"wp:attachment":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media?parent=10003484"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tags?post=10003484"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10003484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}