{"id":11818,"date":"2026-05-06T13:12:20","date_gmt":"2026-05-06T11:12:20","guid":{"rendered":"https:\/\/qzm-rn.de\/?post_type=tribe_events&#038;p=11818"},"modified":"2026-05-06T13:12:25","modified_gmt":"2026-05-06T11:12:25","slug":"queerwolf-3","status":"publish","type":"tribe_events","link":"https:\/\/qzm-rn.de\/en\/veranstaltung\/queerwolf-3\/","title":{"rendered":"Queerwolf"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t22. May\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t19:00\t\t\t<\/span>\n\t\t\n\t\t\t<\/p>\n<\/div>\n\n\n\n<p>Wir nehmen das Spiel \u201cWerw\u00f6lfe von D\u00fcsterwald\u201d und bringen es in unser queeres Universum. Freut euch auf eine ganz besondere Atmosph\u00e4re, wenn wir herausfinden, wer die Queerw\u00f6lfe unter uns sind.<\/p>\n\n\n\n<p>Keine Vorkenntnisse ben\u00f6tigt. \u201cWerwolf\u201d ist ein Gruppenspiel, bei dem vorab und w\u00e4hrenddessen alle Regeln und Spielz\u00fcge erkl\u00e4rt werden.<\/p>\n\n\n\n<p>Das Spiel wird auf Deutsch moderiert.<br>Es ist keine Anmeldung notwendig.<\/p>\n\n\n\n<p>Infos zur Barrierearmut: Das QZM ist stufenlos zug\u00e4nglich und es gibt eine barrierearme Toilette. Fragen zu Barrierearmut und rund ums QZM gerne an info@qzm-rn.de.<\/p>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t\t<span class=\"tribe-block__event-price__cost\"> Free <\/span>\n\t\t<\/div>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/qzm-rn.de\/en\/venue\/qzm\/\" title=\"QZM\">QZM<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">G7 ,14<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Mannheim<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\t<span class=\"tribe-postal-code\">68159<\/span>\n\n\t<span class=\"tribe-country-name\">Deutschland<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__website\"><a href=\"http:\/\/qzm-rn.de\/en\/\" target=\"_self\" rel=\"external\">View Venue Website<\/a><\/span><br \/>\n\t\t\t\n\t<\/div>\n\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdd to calendar\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260522T190000\/20260522T190000&#038;text=Queerwolf&#038;details=%3Cp%3EWir+nehmen+das+Spiel+%E2%80%9CWerw%C3%B6lfe+von+D%C3%BCsterwald%E2%80%9D+und+bringen+es+in+unser+queeres+Universum.+Freut+euch+auf+eine+ganz+besondere+Atmosph%C3%A4re%2C+wenn+wir+herausfinden%2C+wer+die+Queerw%C3%B6lfe+unter+uns+sind.%3C%2Fp%3E+%3Cp%3EKeine+Vorkenntnisse+ben%C3%B6tigt.+%E2%80%9CWerwolf%E2%80%9D+ist+ein+Gruppenspiel%2C+bei+dem+vorab+und+w%C3%A4hrenddessen+alle+Regeln+und+Spielz%C3%BCge+erkl%C3%A4rt+werden.%3C%2Fp%3E+%3Cp%3EDas+Spiel+wird+auf+Deutsch+moderiert.%3Cbr%3EEs+ist+keine+Anmeldung+notwendig.%3C%2Fp%3E+%3Cp%3EInfos+zur+Barrierearmut%3A+Das+QZM+ist+stufenlos+zug%C3%A4nglich+und+es+gibt+eine+barrierearme+Toilette.+Fragen+zu+Barrierearmut+und+rund+ums+QZM+gerne+an+info%40qzm-rn.de.%3C%2Fp%3E+&#038;location=QZM,%20G7%20,14,%20Mannheim,%2068159,%20Deutschland&#038;trp=false&#038;ctz=Europe\/Berlin&#038;sprop=website:https:\/\/qzm-rn.de\/en\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul  class=\"tribe-related-events tribe-clearfix\" >\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-11\/2026-05-14\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2024\/05\/Puppy-Stammtisch-HP-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-11\/2026-05-14\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tPuppy Meet Up\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">14. May @ 18:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/karaoke-party-im-qzm-19\/2026-05-15\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2025\/03\/Karaoke-Hp-1600-x-1066-px-1-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Auf der Graphik erkennt man auf lila-schwarzem Hintergund ein Mikrophon und die Aufschrift &quot;Karaoke - Rock the Stage&quot;.\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/karaoke-party-im-qzm-19\/2026-05-15\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tKaraoke im QZM\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">15. May @ 20:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/public-viewing-des-esc-finale\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2026\/05\/J580010-ESC-FACEBOOK-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/public-viewing-des-esc-finale\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tPublic Viewing des ESC Finale\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">16. May @ 19:00<\/span><\/div>\n<\/li>\n\t<\/ul>","protected":false},"excerpt":{"rendered":"<p>Wir nehmen das Spiel \u201cWerw\u00f6lfe von D\u00fcsterwald\u201d und bringen es in unser queeres Universum. Freut euch auf eine ganz besondere Atmosph\u00e4re, wenn wir herausfinden, wer die Queerw\u00f6lfe unter uns sind.<\/p>","protected":false},"author":13,"featured_media":11819,"template":"","meta":{"_tec_requires_first_save":false,"_eb_attr":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_EventAllDay":false,"_EventTimezone":"Europe\/Berlin","_EventStartDate":"2026-05-22 19:00:00","_EventEndDate":"2026-05-22 19:00:00","_EventStartDateUTC":"2026-05-22 17:00:00","_EventEndDateUTC":"2026-05-22 17:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"0","_EventCostDescription":"","_EventCurrencySymbol":"EUR","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[2523],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[71,34,36,48,10,11],"tribe_events_cat":[530],"class_list":["post-11818","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-lgbti","tag-lsbti","tag-lsbttiq","tag-queer","tag-queeres-zentrum-mannheim","tag-qzm","tribe_events_cat-veranstaltung","cat_veranstaltung"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/11818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":1,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/11818\/revisions"}],"predecessor-version":[{"id":11820,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/11818\/revisions\/11820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media\/11819"}],"wp:attachment":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media?parent=11818"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tags?post=11818"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=11818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}