{"id":12359,"date":"2026-07-14T12:58:18","date_gmt":"2026-07-14T10:58:18","guid":{"rendered":"https:\/\/qzm-rn.de\/?post_type=tribe_events&#038;p=12359"},"modified":"2026-07-14T12:58:19","modified_gmt":"2026-07-14T10:58:19","slug":"buchclub-im-qzm-20","status":"publish","type":"tribe_events","link":"https:\/\/qzm-rn.de\/en\/veranstaltung\/buchclub-im-qzm-20\/","title":{"rendered":"Buchclub im QZM"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t28. July\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t19:00\t\t\t<\/span>\n\t\t\n\t\t\t<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hast du Lust, dich mit anderen Leseratten \u00fcber queer-feministische Themen auszutauschen, diverse B\u00fccher zu entdecken und neue Menschen kennenzulernen? Dann komm zu unserem Buchclub im QZM!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir treffen uns einmal im Monat, um uns gemeinsam \u00fcber ein Buch auszutauschen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Juli lesen wir \u201eEine Hymne an das Leben\u201c von Gis\u00e8le Pelicot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unser Buchclub ist ein Safer Space und es gibt keinen Raum f\u00fcr Vorurteile und Diskriminierung in irgendeiner Form.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Information regarding accessibility: The venue is accessible without stairs and has barrier low toilet.<br>Questions about accessibility at QZM should be addressed to <a href=\"mailto:info@qzm-rn.de\">info@qzm-rn.de<\/a> or 0621 15677628.<\/p>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t\t<span class=\"tribe-block__event-price__cost\"> Free <\/span>\n\t\t<\/div>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/qzm-rn.de\/en\/venue\/__trashed-9\/\" title=\"Queeres Zentrum Mannheim, G7,14, 68159 Mannheim\">Queeres Zentrum Mannheim, G7,14, 68159 Mannheim<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">G7<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Mannheim<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\t<span class=\"tribe-postal-code\">68161<\/span>\n\n\n<\/span>\n\n\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__phone\">06213367333<\/span><br \/>\n\t\t\n\t\t\t\n\t<\/div>\n\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdd to calendar\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewbox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260728T190000\/20260728T190000&#038;text=Buchclub%20im%20QZM&#038;details=%3Cp%3EHast+du+Lust%2C+dich+mit+anderen+Leseratten+%C3%BCber+queer-feministische+Themen+auszutauschen%2C+diverse+B%C3%BCcher+zu+entdecken+und+neue+Menschen+kennenzulernen%3F+Dann+komm+zu+unserem+Buchclub+im+QZM%21%3C%2Fp%3E+%3Cp%3EWir+treffen+uns+einmal+im+Monat%2C+um+uns+gemeinsam+%C3%BCber+ein+Buch+auszutauschen.%3C%2Fp%3E+%3Cp%3EIm+Juli+lesen+wir+%E2%80%9EEine+Hymne+an+das+Leben%E2%80%9C+von+Gis%C3%A8le+Pelicot.%3C%2Fp%3E+%3Cp%3EUnser+Buchclub+ist+ein+Safer+Space+und+es+gibt+keinen+Raum+f%C3%BCr+Vorurteile+und+Diskriminierung+in+irgendeiner+Form.%3C%2Fp%3E+%3Cp%3EInfos+zur+Barrierearmut%3A+Der+Veranstaltungsraum+ist+stufenlos+zug%C3%A4nglich+und+es+gibt+eine+barrierearme+Toilette.%3Cbr%3EFragen+zu+Barrierearmut+im+QZM+gerne+an+%3Ca+href%3D%22mailto%3Ainfo%40qzm-rn.de%22%3Einfo%40qzm-rn.de%3C%2Fa%3E+oder+0621+15677628.%3C%2Fp%3E+&#038;location=Queeres%20Zentrum%20Mannheim,%20G7,14,%2068159%20Mannheim,%20G7,%20Mannheim,%2068161&#038;trp=false&#038;ctz=Europe\/Berlin&#038;sprop=website:https:\/\/qzm-rn.de\/en\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul  class=\"tribe-related-events tribe-clearfix\" >\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/wir-positiv-stammtisch-2\/2026-07-16\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2024\/03\/Design-ohne-Titel-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/wir-positiv-stammtisch-2\/2026-07-16\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tWIR.postiv Meet Up\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">16. July @ 18:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-12\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2025\/05\/Homepage-1-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Die Grafik zeigt ein Gruppenbild der Gruppe im Hintergrund. Es sind die Logos des QZM und der Rhein Neckar Pupies zu sehen. AU\u00dferdem stehen wichtige Dinge wie Titel und Termininfos auf der Grafik.\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/puppy-stammtisch-12\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tPuppy Meet Up\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">16. July @ 18:00<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/qzm-newcomer-abend\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/qzm-rn.de\/wp-content\/uploads\/2026\/07\/Homepage-1024x682.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/qzm-rn.de\/en\/veranstaltung\/qzm-newcomer-abend\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tQZM Newcomer-Abend\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">16. July @ 19:00<\/span><\/div>\n<\/li>\n\t<\/ul>","protected":false},"excerpt":{"rendered":"<p>Hast du Lust, dich mit anderen Leseratten \u00fcber queer-feministische Themen auszutauschen, diverse B\u00fccher zu entdecken und neue Menschen kennenzulernen? Dann komm zu unserem Buchclub im QZM!<br \/>\nIm Juli lesen wir \u201eEine Hymne an das Leben\u201c von Gis\u00e8le Pelicot.<\/p>","protected":false},"author":12,"featured_media":12344,"template":"","meta":{"_tec_requires_first_save":false,"_eb_attr":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_EventAllDay":false,"_EventTimezone":"Europe\/Berlin","_EventStartDate":"2026-07-28 19:00:00","_EventEndDate":"2026-07-28 19:00:00","_EventStartDateUTC":"2026-07-28 17:00:00","_EventEndDateUTC":"2026-07-28 17:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"0","_EventCostDescription":"","_EventCurrencySymbol":"EUR","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[7974],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[871,1082,71,30,34,36,21,48,10,11],"tribe_events_cat":[1040,503,504,530],"class_list":["post-12359","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-buchclub","tag-lektuere","tag-lgbti","tag-lgbttiq","tag-lsbti","tag-lsbttiq","tag-mannheim","tag-queer","tag-queeres-zentrum-mannheim","tag-qzm","tribe_events_cat-get-together","tribe_events_cat-kunst","tribe_events_cat-literatur","tribe_events_cat-veranstaltung","cat_get-together","cat_kunst","cat_literatur","cat_veranstaltung"],"_links":{"self":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/12359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":1,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/12359\/revisions"}],"predecessor-version":[{"id":12360,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events\/12359\/revisions\/12360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media\/12344"}],"wp:attachment":[{"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/media?parent=12359"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tags?post=12359"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/qzm-rn.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=12359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}